{"id":246040,"date":"2020-07-23T17:44:13","date_gmt":"2020-07-23T17:44:13","guid":{"rendered":"https:\/\/staging.mapleleaffoods.com\/fr\/2020\/07\/23\/resume-du-rapport-de-2019-sur-la-durabilite-des-aliments-maple-leaf\/"},"modified":"2024-01-17T15:24:54","modified_gmt":"2024-01-17T20:24:54","slug":"du-rapport-2019-sur-la-durabilite","status":"publish","type":"post","link":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/","title":{"rendered":"R\u00e9sum\u00e9 du rapport de 2019 sur la durabilit\u00e9 des Aliments Maple Leaf"},"content":{"rendered":"<p><strong>Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te<\/strong><\/p>\n<p>Le 7\u00a0juillet, les Aliments Maple Leaf a annonc\u00e9 la publication de son rapport de 2019 sur la durabilit\u00e9. Ce rapport met en lumi\u00e8re ses r\u00e9alisations et programmes importants de la derni\u00e8re ann\u00e9e, ainsi que les initiatives et priorit\u00e9s futures qui lui permettront de devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te.<\/p>\n<p>Les Aliments Maple Leaf a \u00e9largi son engagement \u00e0 l\u2019\u00e9gard de la durabilit\u00e9 et fait des progr\u00e8s consid\u00e9rables tout au long de 2019. Notamment, elle est devenue la premi\u00e8re grande entreprise alimentaire carboneutre au monde et a \u00e9tabli ses objectifs de r\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre \u00e0 partir de donn\u00e9es scientifiques. Elle s\u2019est engag\u00e9e \u00e0 prot\u00e9ger l\u2019environnement parce qu\u2019elle est consciente des ressources n\u00e9cessaires pour produire des aliments prot\u00e9in\u00e9s riches en nutriments et qu\u2019il lui incombe de neutraliser ses r\u00e9percussions sur la nature.<\/p>\n<p>Le programme de durabilit\u00e9 des Aliments Maple Leaf s\u2019appuie sur quatre piliers directeurs\u00a0: de meilleurs aliments, de meilleurs soins, de meilleures collectivit\u00e9s et une meilleure plan\u00e8te. Voici des faits saillants du rapport\u00a0:<\/p>\n<p><strong>De Meilleurs Aliments<\/strong><\/p>\n<p>La d\u00e9finition d\u2019un bon aliment peut changer d\u2019une personne \u00e0 l\u2019autre. N\u00e9anmoins, nous voulons r\u00e9pondre \u00e0 tous les besoins. Nous sommes d\u00e9termin\u00e9s \u00e0 offrir aux consommateurs des aliments d\u00e9licieux compos\u00e9s d\u2019ingr\u00e9dients naturels et leur procurant une bonne valeur nutritive, et \u00e0 fabriquer ces produits dans un environnement de travail s\u00e9curitaire.<\/p>\n<ul>\n<li>Nous avons inclus notre marque Prime<sup>MD<\/sup> dans notre programme \u00c9lev\u00e9s sans antibiotiques dans l\u2019Ouest du Canada et lanc\u00e9 notre marque biologique Prime<sup>MD<\/sup>.<\/li>\n<li>Nous sommes demeur\u00e9s le plus grand producteur de porcs \u00e9lev\u00e9s sans antibiotiques en Am\u00e9rique du Nord et le plus grand producteur de volaille \u00e9lev\u00e9e sans antibiotique au Canada.<\/li>\n<\/ul>\n<ul>\n<li>Nous avons renforc\u00e9 notre position de chef de file dans le secteur des prot\u00e9ines v\u00e9g\u00e9tales\u00a0: en 2019, nous avons mis \u00e0 l\u2019essai le Maple Leaf\u00ae, contenant des ingr\u00e9dients v\u00e9g\u00e9taux naturels et 50\u00a0% moins de viande.<\/li>\n<li>Nous avons mis en \u0153uvre notre programme de formation de classe mondiale Analyse des risques et ma\u00eetrise des points critiques dans toutes nos usines.<\/li>\n<li>Nous avons ex\u00e9cut\u00e9 plus de 211\u00a0000\u00a0tests de salubrit\u00e9 alimentaire sans avoir \u00e0 faire de rappel de produit.<\/li>\n<li>Nous avons d\u00e9pass\u00e9 nos objectifs en mati\u00e8re de taux d\u2019incidents li\u00e9s \u00e0 la salubrit\u00e9 alimentaire de 53\u00a0% et de taux d\u2019incidents li\u00e9s \u00e0 la qualit\u00e9 de 15\u00a0%.<\/li>\n<li>Nous avons continu\u00e9 de mettre en application notre credo alimentaire et nos principes de durabilit\u00e9 en mati\u00e8re de viande.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"size-full wp-image-242472 aligncenter\" src=\"\/wp-content\/uploads\/2020\/08\/MLF_BetterFood_Blog.jpg\" alt=\"Image Better Food Sandwich\" width=\"766\" height=\"388\" srcset=\"https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterFood_Blog.jpg?lossy=1&amp;strip=1&amp;webp=1 766w, https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterFood_Blog-300x152.jpg?lossy=1&amp;strip=1&amp;webp=1 300w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/p>\n<p><strong>De Meilleurs Soins<\/strong><\/p>\n<p>Nous poss\u00e9dons de solides valeurs qui d\u00e9finissent notre culture et notre fa\u00e7on de mener nos activit\u00e9s. Ces valeurs d\u00e9terminent \u00e9galement comment nous traitons les animaux que nous \u00e9levons ou achetons et refl\u00e8tent notre objectif de devenir un chef de file en mati\u00e8re de bien-\u00eatre animal.<\/p>\n<ul>\n<li>Nous avons transf\u00e9r\u00e9 50\u00a0000 (77\u00a0%)\u00a0truies vers notre syst\u00e8me de logement libre de pointe pour les truies \u00e0 ce jour.<\/li>\n<li>Nous avons fourni des jouets afin d\u2019enrichir l\u2019environnement des porcs en croissance dans 90\u00a0% de nos installations.<\/li>\n<li>Toutes nos remorques pour porcs sont dot\u00e9es d\u2019un syst\u00e8me de plateforme hydraulique.<\/li>\n<li>Nous avons r\u00e9duit notre utilisation d\u2019antibiotiques de 63\u00a0% dans les porcheries que nous poss\u00e9dons.<\/li>\n<li>Nous nous sommes engag\u00e9s \u00e0 am\u00e9liorer nos pratiques favorisant le bien-\u00eatre animal de mani\u00e8re \u00e0 promouvoir les cinq\u00a0libert\u00e9s et notre culture tient compte des cinq\u00a0domaines du bien-\u00eatre animal.<\/li>\n<li>Nous avons enti\u00e8rement converti notre \u00e9tablissement de transformation de volaille d\u2019Edmonton en abattoir \u00e0 atmosph\u00e8re contr\u00f4l\u00e9e.<\/li>\n<li>Les employ\u00e9s qui manipulent les animaux ont suivi les modules de formation sur le bien-\u00eatre animal.<\/li>\n<li>Nous avons continu\u00e9 de travailler avec le comit\u00e9 consultatif sur le bien-\u00eatre animal des Aliments Maple Leaf afin de recommander des pratiques exemplaires, des recherches scientifiques et des innovations pour nous am\u00e9liorer continuellement.<\/li>\n<li>Nous avons continu\u00e9 de mettre en application et de communiquer nos r\u00e8gles d\u2019or et notre engagement en mati\u00e8re de bien-\u00eatre animal.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"size-full wp-image-242470 aligncenter\" src=\"\/wp-content\/uploads\/2020\/08\/MLF_BetterCare_Blog.jpg\" alt=\"Image Better Care poultry facility\" width=\"766\" height=\"390\" srcset=\"https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterCare_Blog.jpg?lossy=1&amp;strip=1&amp;webp=1 766w, https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterCare_Blog-300x153.jpg?lossy=1&amp;strip=1&amp;webp=1 300w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/p>\n<p><strong>De Meilleures Collectivit\u00e9s<\/strong><\/p>\n<p>Nous attachons une grande valeur aux collectivit\u00e9s et travaillons en collaboration avec des organismes \u00e0 r\u00e9duire l\u2019ins\u00e9curit\u00e9 alimentaire au Canada. Nous valorisons une culture et un environnement de travail qui assurent la s\u00e9curit\u00e9 des employ\u00e9s, r\u00e9compensent l\u2019excellence, favorisent l\u2019apprentissage et permettent \u00e0 chaque personne de donner le meilleur d\u2019elle-m\u00eame.<\/p>\n<ul>\n<li>Nous avons vers\u00e9 plus de 2,3\u00a0millions de dollars \u00e0 des initiatives favorisant la s\u00e9curit\u00e9 alimentaire. De plus, nous avons donn\u00e9 des produits sains d\u2019une valeur de plus de 1,6\u00a0million de dollars \u00e0 des organismes dot\u00e9s de grands r\u00e9seaux de distribution leur permettant de joindre les personnes d\u00e9favoris\u00e9es.<\/li>\n<li>Durant la p\u00e9riode des \u00e9lections f\u00e9d\u00e9rales, nous avons cr\u00e9\u00e9 #anticanadien, une campagne de sensibilisation \u00e0 l\u2019ins\u00e9curit\u00e9 alimentaire au Canada s\u2019\u00e9tant d\u00e9roul\u00e9e sur les m\u00e9dias sociaux. En trois\u00a0semaines, nous avons r\u00e9colt\u00e9 11,5\u00a0millions de r\u00e9actions, plus de 65\u00a0000\u00a0r\u00e9ponses \u00e0 nos questions de sondage et au-del\u00e0 de 1,4\u00a0million de vues, dont plus de 500\u00a0000\u00a0visionnements complets.<\/li>\n<li>Le Centre d\u2019action de Maple Leaf pour la s\u00e9curit\u00e9 alimentaire a conclu des partenariats avec 19\u00a0organismes d\u2019un bout \u00e0 l\u2019autre du pays afin de promouvoir la s\u00e9curit\u00e9 alimentaire.<\/li>\n<li>Le Centre a donn\u00e9 10\u00a0000\u00a0$ au programme Bahamas de l\u2019organisme The Nature Conservancy afin de soutenir la lutte contre les changements climatiques apr\u00e8s le passage de l\u2019ouragan Dorian.<\/li>\n<li>Nous avons r\u00e9duit les blessures avec perte de temps \u00e0 z\u00e9ro dans 21\u00a0installations qui sont devenues membres de notre Club des h\u00e9ros de la s\u00e9curit\u00e9.<\/li>\n<li>Nous avons obtenu un taux total d\u2019incidents enregistrables de 0,60 et un taux de jours d\u2019absence, d\u2019activit\u00e9s restreintes ou de transferts (DART) de 0,21.<\/li>\n<li>Nous avons r\u00e9ussi \u00e0 ex\u00e9cuter 97\u00a0% des plans annuels de sant\u00e9, de s\u00e9curit\u00e9 et de r\u00e9duction des accidents dans nos usines.<\/li>\n<li>Nous avons atteint un taux de repr\u00e9sentation des femmes de 38\u00a0% au sein de la direction, une hausse par rapport au taux de 36\u00a0% de 2017.<\/li>\n<li>Nous avons lanc\u00e9 l\u2019initiative de sant\u00e9 mentale Vous n\u2019\u00eates pas seul pour b\u00e2tir une culture qui rejette les pr\u00e9jug\u00e9s associ\u00e9s aux probl\u00e8mes de sant\u00e9 mentale.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"size-full wp-image-242480 aligncenter\" src=\"\/wp-content\/uploads\/2020\/08\/MLF_BetterCommunities_Blog.jpg\" alt=\"Image Better Communities - family planting vegetable\" width=\"766\" height=\"388\" srcset=\"https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterCommunities_Blog.jpg?lossy=1&amp;strip=1&amp;webp=1 766w, https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterCommunities_Blog-300x152.jpg?lossy=1&amp;strip=1&amp;webp=1 300w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/p>\n<p><strong>Une\u00a0Meilleure Plan\u00e8te<\/strong><\/p>\n<p>\u00catre un chef de file en mati\u00e8re de durabilit\u00e9 n\u2019est pas qu\u2019une de nos strat\u00e9gies principales, mais aussi une vision d\u2019entreprise qui tient compte de chaque aspect de nos activit\u00e9s.<\/p>\n<ul>\n<li>Nous sommes devenus la premi\u00e8re grande entreprise alimentaire carboneutre au monde.<\/li>\n<li>Nous figurons maintenant parmi les trois\u00a0seules entreprises canadiennes \u00e0 avoir \u00e9tabli des objectifs fond\u00e9s sur des donn\u00e9es scientifiques approuv\u00e9s par l\u2019initiative Science Based Targets.<\/li>\n<li>Depuis 2014, nous avons r\u00e9duit notre consommation d\u2019\u00e9lectricit\u00e9 de 22\u00a0%, de gaz naturel de 10\u00a0% et d\u2019eau de 17\u00a0%, ainsi que notre production de d\u00e9chets solides de 19\u00a0%.<\/li>\n<li>Nous avons atteint un taux de r\u00e9acheminement des d\u00e9chets de 90,7\u00a0% \u00e0 l\u2019\u00e9chelle de l\u2019entreprise.<\/li>\n<li>Notre strat\u00e9gie cadre avec les objectifs de d\u00e9veloppement durable des Nations Unies, et nous avons contribu\u00e9 \u00e0 l\u2019atteinte de 12\u00a0d\u2019entre eux.<\/li>\n<li>Nous avons r\u00e9duit de 40\u00a0% le poids des mat\u00e9riaux d\u2019emballage des trousses-repas de Maple Leaf\u00ae et de 14\u00a0% en moyenne le poids des mat\u00e9riaux d\u2019emballage de nos produits de volaille transform\u00e9s Prime<sup>MD<\/sup> de Maple Leaf.<\/li>\n<li>Nous avons utilis\u00e9 un emballage enti\u00e8rement recyclable pour notre p\u00e2t\u00e9 au poulet miniature Premium de Swift\u00ae et des barquettes enti\u00e8rement recyclables faites de 95\u00a0% de contenu recycl\u00e9 pour nos hauts de cuisse de poulet biologiques d\u00e9soss\u00e9s et sans peau Prime<sup>MD<\/sup> de Maple Leaf, notre burger \u00e0 base v\u00e9g\u00e9tale Lightlife<sup>MC<\/sup> et notre porc frais Greenfield<sup>\u00ae<\/sup>.<\/li>\n<li>Notre entreprise est devenue la premi\u00e8re du secteur alimentaire canadien \u00e0 \u00e9tablir un partenariat avec <a href=\"https:\/\/fr.how2recycle.info\/\">How2Recycle<\/a> et la premi\u00e8re du secteur alimentaire \u00e0 en conclure un avec <a href=\"https:\/\/www.loopindustries.com\">Loop<\/a>.<\/li>\n<li>Nous sommes membres de plusieurs organisations et avons particip\u00e9 \u00e0 divers programmes pour diffuser les connaissances et favoriser la collaboration afin de r\u00e9gler les probl\u00e8mes de cha\u00eene d\u2019approvisionnement.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"size-full wp-image-242474 aligncenter\" src=\"\/wp-content\/uploads\/2020\/08\/MLF_BetterPlanet_Blog.jpg\" alt=\"Image Better Planet - crops\" width=\"766\" height=\"388\" srcset=\"https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterPlanet_Blog.jpg?lossy=1&amp;strip=1&amp;webp=1 766w, https:\/\/b3412141.smushcdn.com\/3412141\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_BetterPlanet_Blog-300x152.jpg?lossy=1&amp;strip=1&amp;webp=1 300w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/p>\n<p>Les Aliments Maple Leaf travaille continuellement \u00e0 am\u00e9liorer la durabilit\u00e9 de la production et du syst\u00e8me alimentaires. \u00c0 cette fin, nous nous attaquons aux enjeux environnementaux et sociaux importants auxquels la soci\u00e9t\u00e9 est confront\u00e9e. Nous sommes d\u00e9termin\u00e9s \u00e0 cr\u00e9er des valeurs communes, ce qui est selon nous essentiel \u00e0 la viabilit\u00e9 de notre entreprise et \u00e0 la durabilit\u00e9 de l\u2019environnement. Nous continuons de tout mettre en \u0153uvre pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable de la plan\u00e8te.<\/p>\n<p>Pour voir le rapport complet sur la durabilit\u00e9 de 2019, <a href=\"https:\/\/www.mapleleaffoods.com\/fr\/nos-engagements\/\">cliquez ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te<\/p>\n","protected":false},"author":18,"featured_media":242477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"mlfcorp_iframe_url":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-246040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-engagements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf<\/title>\n<meta name=\"description\" content=\"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf\" \/>\n<meta property=\"og:description\" content=\"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Aliments Maple Leaf\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T17:44:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-17T20:24:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2222\" \/>\n\t<meta property=\"og:image:height\" content=\"1622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jclaussen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"jclaussen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\"},\"author\":{\"name\":\"jclaussen\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/ec41dbb99ad6eb87d278885b9abec7e3\"},\"headline\":\"R\u00e9sum\u00e9 du rapport de 2019 sur la durabilit\u00e9 des Aliments Maple Leaf\",\"datePublished\":\"2020-07-23T17:44:13+00:00\",\"dateModified\":\"2024-01-17T20:24:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\"},\"wordCount\":1503,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg\",\"articleSection\":[\"Nos engagements\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\",\"url\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\",\"name\":\"R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf\",\"isPartOf\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg\",\"datePublished\":\"2020-07-23T17:44:13+00:00\",\"dateModified\":\"2024-01-17T20:24:54+00:00\",\"description\":\"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage\",\"url\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg\",\"contentUrl\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg\",\"width\":2222,\"height\":1622,\"caption\":\"Large Open Field\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d\u2019accueil\",\"item\":\"https:\/\/www.mapleleaffoods.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sum\u00e9 du rapport de 2019 sur la durabilit\u00e9 des Aliments Maple Leaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#website\",\"url\":\"https:\/\/www.mapleleaffoods.com\/fr\/\",\"name\":\"Les Aliments Maple Leaf\",\"description\":\"Premi\u00e8re grande entreprise alimentaire carboneutre au monde\",\"publisher\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mapleleaffoods.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#organization\",\"name\":\"Les Aliments Maple Leaf\",\"url\":\"https:\/\/www.mapleleaffoods.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2026\/07\/cropped-MLF-Logo-Website-250x250-1.png\",\"contentUrl\":\"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2026\/07\/cropped-MLF-Logo-Website-250x250-1.png\",\"width\":250,\"height\":250,\"caption\":\"Les Aliments Maple Leaf\"},\"image\":{\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/ec41dbb99ad6eb87d278885b9abec7e3\",\"name\":\"jclaussen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/08d5158143d6a2857f125fd0a4e45f83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/08d5158143d6a2857f125fd0a4e45f83?s=96&d=mm&r=g\",\"caption\":\"jclaussen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf","description":"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf","og_description":"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...","og_url":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/","og_site_name":"Les Aliments Maple Leaf","article_published_time":"2020-07-23T17:44:13+00:00","article_modified_time":"2024-01-17T20:24:54+00:00","og_image":[{"width":2222,"height":1622,"url":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","type":"image\/jpeg"}],"author":"jclaussen","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"jclaussen","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#article","isPartOf":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/"},"author":{"name":"jclaussen","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/ec41dbb99ad6eb87d278885b9abec7e3"},"headline":"R\u00e9sum\u00e9 du rapport de 2019 sur la durabilit\u00e9 des Aliments Maple Leaf","datePublished":"2020-07-23T17:44:13+00:00","dateModified":"2024-01-17T20:24:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/"},"wordCount":1503,"commentCount":0,"publisher":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","articleSection":["Nos engagements"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/","url":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/","name":"R\u00e9sum\u00e9 Du Rapport De 2019 Sur La Durabilit\u00e9 Des Aliments Maple Leaf","isPartOf":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage"},"image":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","datePublished":"2020-07-23T17:44:13+00:00","dateModified":"2024-01-17T20:24:54+00:00","description":"Notre parcours pour devenir l\u2019entreprise de produits de prot\u00e9ines la plus durable sur la plan\u00e8te. Le 7\u00a0juillet, les Aliments Maple Leaf...","breadcrumb":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#primaryimage","url":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","contentUrl":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","width":2222,"height":1622,"caption":"Large Open Field"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mapleleaffoods.com\/fr\/articles-de-fond\/du-rapport-2019-sur-la-durabilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d\u2019accueil","item":"https:\/\/www.mapleleaffoods.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sum\u00e9 du rapport de 2019 sur la durabilit\u00e9 des Aliments Maple Leaf"}]},{"@type":"WebSite","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#website","url":"https:\/\/www.mapleleaffoods.com\/fr\/","name":"Les Aliments Maple Leaf","description":"Premi\u00e8re grande entreprise alimentaire carboneutre au monde","publisher":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mapleleaffoods.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#organization","name":"Les Aliments Maple Leaf","url":"https:\/\/www.mapleleaffoods.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2026\/07\/cropped-MLF-Logo-Website-250x250-1.png","contentUrl":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2026\/07\/cropped-MLF-Logo-Website-250x250-1.png","width":250,"height":250,"caption":"Les Aliments Maple Leaf"},"image":{"@id":"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/ec41dbb99ad6eb87d278885b9abec7e3","name":"jclaussen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mapleleaffoods.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/08d5158143d6a2857f125fd0a4e45f83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08d5158143d6a2857f125fd0a4e45f83?s=96&d=mm&r=g","caption":"jclaussen"}}]}},"jetpack_featured_media_url":"https:\/\/www.mapleleaffoods.com\/fr\/wp-content\/uploads\/sites\/7\/2020\/08\/MLF_Main_Blog_Sustainability.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/posts\/246040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/comments?post=246040"}],"version-history":[{"count":7,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/posts\/246040\/revisions"}],"predecessor-version":[{"id":256075,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/posts\/246040\/revisions\/256075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/media\/242477"}],"wp:attachment":[{"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/media?parent=246040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/categories?post=246040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mapleleaffoods.com\/fr\/wp-json\/wp\/v2\/tags?post=246040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}